{"id":27,"count":4,"description":"","link":"https:\/\/universogestion.cl\/propiedades\/caracteristica\/secadora\/","name":"Secadora","slug":"secadora","taxonomy":"property_feature","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/universogestion.cl\/propiedades\/wp-json\/wp\/v2\/property_feature\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/universogestion.cl\/propiedades\/wp-json\/wp\/v2\/property_feature"}],"about":[{"href":"https:\/\/universogestion.cl\/propiedades\/wp-json\/wp\/v2\/taxonomies\/property_feature"}],"wp:post_type":[{"href":"https:\/\/universogestion.cl\/propiedades\/wp-json\/wp\/v2\/properties?property_feature=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}